{"id":54,"date":"2018-06-07T15:58:48","date_gmt":"2018-06-07T13:58:48","guid":{"rendered":"https:\/\/www.petingros.it\/animali\/?p=54"},"modified":"2019-02-04T11:20:43","modified_gmt":"2019-02-04T10:20:43","slug":"animali-che-iniziano-con-la-k","status":"publish","type":"post","link":"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/","title":{"rendered":"Animali che iniziano con la K"},"content":{"rendered":"<h2><a href=\"https:\/\/it.wikipedia.org\/wiki\/Phascolarctos_cinereus\">Koala<\/a><\/h2>\n<figure id=\"attachment_474\" aria-describedby=\"caption-attachment-474\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/koala.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-474 size-thumbnail\" src=\"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/koala-150x150.jpg\" alt=\"mammifero di piccola taglia.\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-474\" class=\"wp-caption-text\">koala<\/figcaption><\/figure>\n<p>E&#8217; un mammifero australiano, appartiene alla propria famiglia chiamata Phascolarctidae. Ha grandi orecchie rotonde e pelose, ha una grossa testa,\u00a0 ha un muso largo, naso schiacciato e nudo. Ha la pelle di colore grigio chiaro con ciuffi di colore bianco. Ha 5 dita prensili nelle zampe, e la sua dieta \u00e8 l&#8217;eucalipto.<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/1R-QFQGWYuc\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><!--more--><\/p>\n<h2><a href=\"https:\/\/en.wikipedia.org\/wiki\/Kookaburra\">Kookaburra<\/a><\/h2>\n<figure id=\"attachment_476\" aria-describedby=\"caption-attachment-476\" style=\"width: 147px\" class=\"wp-caption alignright\"><a href=\"https:\/\/en.wikipedia.org\/wiki\/Kookaburra\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-476 \" src=\"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/kokaburra-300x225.jpg\" alt=\"volatile di piccole dimensioni\" width=\"147\" height=\"110\" srcset=\"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/kokaburra-300x225.jpg 300w, https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/kokaburra-600x450.jpg 600w, https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/kokaburra-768x576.jpg 768w, https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/kokaburra-164x124.jpg 164w, https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/kokaburra.jpg 800w\" sizes=\"(max-width: 147px) 100vw, 147px\" \/><\/a><figcaption id=\"caption-attachment-476\" class=\"wp-caption-text\">Kookaburra<\/figcaption><\/figure>\n<p>I\u00a0 kookaburra sono carnivori ed insettivori\u00a0 si nutrono di lucertole, serpenti piccoli, insetti e topi. Non ha paura del uomo, questo volatile si trova in Australia.<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/TqdRQxgtZtI\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<figure id=\"attachment_537\" aria-describedby=\"caption-attachment-537\" style=\"width: 147px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/Kancil-malese.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-537 \" src=\"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/Kancil-malese-300x237.jpg\" alt=\"Il Kancil Malese ha il pelo corto \" width=\"147\" height=\"116\" \/><\/a><figcaption id=\"caption-attachment-537\" class=\"wp-caption-text\">Kancil Malese<\/figcaption><\/figure>\n<h2><a href=\"https:\/\/it.wikipedia.org\/wiki\/Tragulus_napu\">Kancil Malese<\/a><\/h2>\n<p>Il Kancil Malese\u00a0appartiene all&#8217;ordine degli Artiodattili, \u00e8 diffuso in Asia sud-orientale e meridionale e alcune specie in Africa. vive in coppia e si nutrono di erba, foglie o quasi tutto ci\u00f2 vegetale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Koala E&#8217; un mammifero australiano, appartiene alla propria famiglia chiamata Phascolarctidae. Ha grandi orecchie rotonde e pelose, ha una grossa testa,\u00a0 ha un muso largo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pg_page_styles":[],"footnotes":""},"categories":[2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Animali che iniziano con la K - Animali con la<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Animali che iniziano con la K - Animali con la\" \/>\n<meta property=\"og:description\" content=\"Koala E&#8217; un mammifero australiano, appartiene alla propria famiglia chiamata Phascolarctidae. Ha grandi orecchie rotonde e pelose, ha una grossa testa,\u00a0 ha un muso largo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/\" \/>\n<meta property=\"og:site_name\" content=\"Animali con la\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-07T13:58:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-04T10:20:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/Koala.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_pet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_pet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/\",\"url\":\"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/\",\"name\":\"Animali che iniziano con la K - Animali con la\",\"isPartOf\":{\"@id\":\"https:\/\/www.petingros.it\/animali\/#website\"},\"datePublished\":\"2018-06-07T13:58:48+00:00\",\"dateModified\":\"2019-02-04T10:20:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.petingros.it\/animali\/#\/schema\/person\/249c8fd7a089e34304ce5e5e370a5087\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.petingros.it\/animali\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Animali che iniziano con la K\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.petingros.it\/animali\/#website\",\"url\":\"https:\/\/www.petingros.it\/animali\/\",\"name\":\"Animali con la\",\"description\":\"Informazioni su cani, gatti, acquari o animali in genere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.petingros.it\/animali\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.petingros.it\/animali\/#\/schema\/person\/249c8fd7a089e34304ce5e5e370a5087\",\"name\":\"admin_pet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.petingros.it\/animali\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9cc5fd50c6c28054c996d384d2748333?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9cc5fd50c6c28054c996d384d2748333?s=96&d=mm&r=g\",\"caption\":\"admin_pet\"},\"url\":\"https:\/\/www.petingros.it\/animali\/author\/admin_pet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Animali che iniziano con la K - Animali con la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/","og_locale":"it_IT","og_type":"article","og_title":"Animali che iniziano con la K - Animali con la","og_description":"Koala E&#8217; un mammifero australiano, appartiene alla propria famiglia chiamata Phascolarctidae. Ha grandi orecchie rotonde e pelose, ha una grossa testa,\u00a0 ha un muso largo, [&hellip;]","og_url":"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/","og_site_name":"Animali con la","article_published_time":"2018-06-07T13:58:48+00:00","article_modified_time":"2019-02-04T10:20:43+00:00","og_image":[{"width":650,"height":340,"url":"https:\/\/www.petingros.it\/animali\/wp-content\/uploads\/2018\/06\/Koala.jpg","type":"image\/jpeg"}],"author":"admin_pet","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin_pet","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/","url":"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/","name":"Animali che iniziano con la K - Animali con la","isPartOf":{"@id":"https:\/\/www.petingros.it\/animali\/#website"},"datePublished":"2018-06-07T13:58:48+00:00","dateModified":"2019-02-04T10:20:43+00:00","author":{"@id":"https:\/\/www.petingros.it\/animali\/#\/schema\/person\/249c8fd7a089e34304ce5e5e370a5087"},"breadcrumb":{"@id":"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.petingros.it\/animali\/animali-che-iniziano-con-la-k\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.petingros.it\/animali\/"},{"@type":"ListItem","position":2,"name":"Animali che iniziano con la K"}]},{"@type":"WebSite","@id":"https:\/\/www.petingros.it\/animali\/#website","url":"https:\/\/www.petingros.it\/animali\/","name":"Animali con la","description":"Informazioni su cani, gatti, acquari o animali in genere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.petingros.it\/animali\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.petingros.it\/animali\/#\/schema\/person\/249c8fd7a089e34304ce5e5e370a5087","name":"admin_pet","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.petingros.it\/animali\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9cc5fd50c6c28054c996d384d2748333?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9cc5fd50c6c28054c996d384d2748333?s=96&d=mm&r=g","caption":"admin_pet"},"url":"https:\/\/www.petingros.it\/animali\/author\/admin_pet\/"}]}},"_links":{"self":[{"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/posts\/54"}],"collection":[{"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":18,"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"predecessor-version":[{"id":750,"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/posts\/54\/revisions\/750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/media\/142"}],"wp:attachment":[{"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petingros.it\/animali\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}